{"id":2879,"date":"2016-07-27T00:00:00","date_gmt":"2016-07-27T00:00:00","guid":{"rendered":"https:\/\/borges.es\/blog\/quatre-vinagretes-imprescindibles\/"},"modified":"2018-06-05T14:16:10","modified_gmt":"2018-06-05T14:16:10","slug":"quatre-vinagretes-imprescindibles","status":"publish","type":"post","link":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/","title":{"rendered":"Quatre vinagretes imprescindibles a la teva taula"},"content":{"rendered":"<p>Tenen molt sabor, donen color als teus plats i t\u2019ajuden a dur una dieta equilibrada. Pocs aliments donen tant joc com les vinagretes. Durant els \u00faltims anys, aquestes delicioses emulsions elaborades a partir d\u2019una base de vinagre i oli d\u2019oliva verge extra \u2013a la que s\u2019hi poden afegir molts altres ingredients- s\u2019han popularitzat tant que, a l\u2019actualitat, s\u00f3n el principal condiment utilitzat a la nostra cuina.<\/p>\n<p>I \u00e9s que, m\u00e9s enll\u00e0 d\u2019amanir les amanides, les vinagretes s\u00f3n ideals per donar un toc especial a carns, peixos, pastes, arrossos i&#8230; a qualsevol aliment que et puguis imaginar! Has provat mai de marinar un formatge? Afegeix-li un rajol\u00ed d\u2019oli d\u2019oliva verge extra, vinagre de Xer\u00e8s, mel i un pessic de les teves herbes preferides, tot ben barrejat, i et sorprendr\u00e0 descobrir com la teva experi\u00e8ncia de gustos canvia a cada mos. Les vinagretes, a m\u00e9s, aporten molt poques calories a la dieta, al contrari del que se sol pensar.<\/p>\n<p>No necessitem m\u00e9s motius per provar les noves vinagretes de Borges, elaborades amb els millors olis i vinagres i una selecci\u00f3 d\u2019ingredients 100% naturals. Quatre varietats que reuneixen el millor de Borges en tots els sentits:<\/p>\n<p><strong><span style=\"color: #ff0000;\">Vinagreta de M\u00f2dena<\/span><\/strong><br \/>El cl\u00e0ssic vinagre bals\u00e0mic de M\u00f2dena per\u00f2 amb les propietats afegides de l\u2019oli d\u2019oliva verge extra i el contrast del pebre negre amb a mel. \u00c9s una emulsi\u00f3 amb personalitat \u00fanica que serveix tant per amanir com per experimentar amb altres salses t\u00edpiques de la nostra gastronomia, com la salsa rosa que acompanya un c\u00f2ctel de mariscs, entre altres plats.<\/p>\n<p><strong><span style=\"color: #ff0000;\">Vinagreta Mediterr\u00e0nia<\/span><\/strong><br \/>Per a tots aquells als que els agradin les vinagretes amb car\u00e0cter, Borges ha ideat aquesta original mescla d\u2019oli d\u2019oliva verge extra, vinagre de Xer\u00e8s, tom\u00e0quet, olives negres, t\u00e0peres, orenga, nyora i farigola. Combina molt b\u00e9 amb amanides amb formatge i fruits secs o b\u00e9 de pasta i ingredients salts com les anxoves o la tonyina, per\u00f2 tamb\u00e9 les pots utilitzar per condimentar els teus aperitius. Prova-la a la salsa de les patates braves o amb unes escopinyes.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Vinagreta de Llimona<\/strong><\/span><br \/>M\u00e9s enll\u00e0 dels seus usos medicinals i terap\u00e8utics \u2013t\u00e9 un alt contingut en vitamines i propietats antis\u00e8ptiques i bactericides-, la llimona \u00e9s una de les vinagretes m\u00e9s senzilles i saboroses de la nostra gastronomia. Si a m\u00e9s li afegim oli d\u2019oliva verge extra, oli essencial de pell de llimona i un toc de pebre, li estem donant un toc molt diferent a plats tan senzills com una amanida o unes verdures bullides, per\u00f2 tamb\u00e9, perqu\u00e8 no, a un hummus o un taboul\u00e9.<\/p>\n<p><strong><span style=\"color: #ff0000;\">Vinagreta de Soja<\/span><\/strong><br \/>Una sorprenent vinagreta amb aut\u00e8ntic vinagre d\u2019arr\u00f2s, oli d\u2019oliva verge extra, salsa de soja lliure d\u2019organismes modificats gen\u00e8ticament, s\u00e8sam torrat i mel. Una combinaci\u00f3 \u00fanica que permet gaudir de tot el sabor de la salsa de soja per\u00f2 amb un punt menys salat perqu\u00e8 la puguis fer servir en qualsevol plat: amanides, carns peixos, arrossos, pastes i incl\u00fas verdures.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tenen molt sabor, donen color als teus plats i t\u2019ajuden a dur una dieta equilibrada. Pocs aliments donen tant joc&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[1968,549,552,569,574,647,790,941,1773,1784,1869,1888,1892,1949,1954,1969],"class_list":["post-2879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-ca","tag-condimentar","tag-miel-ca","tag-mel","tag-limon-ca","tag-llimona","tag-amanida","tag-soja","tag-ensalada-ca","tag-mediterrani","tag-oli","tag-amanir","tag-estiu","tag-borges","tag-vinagretes","tag-mediterrania","tag-vinagre-de-modena"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quatre vinagretes imprescindibles a la teva taula - Borges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quatre vinagretes imprescindibles a la teva taula - Borges\" \/>\n<meta property=\"og:description\" content=\"Tenen molt sabor, donen color als teus plats i t\u2019ajuden a dur una dieta equilibrada. Pocs aliments donen tant joc...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/\" \/>\n<meta property=\"og:site_name\" content=\"Borges\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-27T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-05T14:16:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/COLLAGE-DELISSIMOS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mortensen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"mortensen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/\"},\"author\":{\"name\":\"mortensen\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\"},\"headline\":\"Quatre vinagretes imprescindibles a la teva taula\",\"datePublished\":\"2016-07-27T00:00:00+00:00\",\"dateModified\":\"2018-06-05T14:16:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/\"},\"wordCount\":535,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/06\\\/COLLAGE-DELISSIMOS.jpg\",\"keywords\":[\"condimentar\",\"miel\",\"mel\",\"lim\u00f3n\",\"llimona\",\"amanida\",\"soja\",\"ensalada\",\"mediterrani\",\"oli\",\"amanir\",\"estiu\",\"borges\",\"vinagretes\",\"mediterr\u00e0nia\",\"vinagre de m\u00f2dena\"],\"articleSection\":[\"Uncategorized @ca\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/\",\"url\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/\",\"name\":\"Quatre vinagretes imprescindibles a la teva taula - Borges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/06\\\/COLLAGE-DELISSIMOS.jpg\",\"datePublished\":\"2016-07-27T00:00:00+00:00\",\"dateModified\":\"2018-06-05T14:16:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/06\\\/COLLAGE-DELISSIMOS.jpg\",\"contentUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/06\\\/COLLAGE-DELISSIMOS.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/quatre-vinagretes-imprescindibles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/borges.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quatre vinagretes imprescindibles a la teva taula\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/borges.es\\\/ca\\\/\",\"name\":\"Borges\",\"description\":\"Aqu\u00ed disfrutamos de la cocina saludable y sabrosa. \u00bfTe apuntas?\",\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\",\"name\":\"mortensen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"caption\":\"mortensen\"},\"url\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/author\\\/mortensen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quatre vinagretes imprescindibles a la teva taula - Borges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/","og_locale":"ca_ES","og_type":"article","og_title":"Quatre vinagretes imprescindibles a la teva taula - Borges","og_description":"Tenen molt sabor, donen color als teus plats i t\u2019ajuden a dur una dieta equilibrada. Pocs aliments donen tant joc...","og_url":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/","og_site_name":"Borges","article_published_time":"2016-07-27T00:00:00+00:00","article_modified_time":"2018-06-05T14:16:10+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/COLLAGE-DELISSIMOS.jpg","type":"image\/jpeg"}],"author":"mortensen","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"mortensen","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/#article","isPartOf":{"@id":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/"},"author":{"name":"mortensen","@id":"https:\/\/borges.es\/ca\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60"},"headline":"Quatre vinagretes imprescindibles a la teva taula","datePublished":"2016-07-27T00:00:00+00:00","dateModified":"2018-06-05T14:16:10+00:00","mainEntityOfPage":{"@id":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/"},"wordCount":535,"commentCount":0,"image":{"@id":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/#primaryimage"},"thumbnailUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/COLLAGE-DELISSIMOS.jpg","keywords":["condimentar","miel","mel","lim\u00f3n","llimona","amanida","soja","ensalada","mediterrani","oli","amanir","estiu","borges","vinagretes","mediterr\u00e0nia","vinagre de m\u00f2dena"],"articleSection":["Uncategorized @ca"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/","url":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/","name":"Quatre vinagretes imprescindibles a la teva taula - Borges","isPartOf":{"@id":"https:\/\/borges.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/#primaryimage"},"image":{"@id":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/#primaryimage"},"thumbnailUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/COLLAGE-DELISSIMOS.jpg","datePublished":"2016-07-27T00:00:00+00:00","dateModified":"2018-06-05T14:16:10+00:00","author":{"@id":"https:\/\/borges.es\/ca\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60"},"breadcrumb":{"@id":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/#primaryimage","url":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/COLLAGE-DELISSIMOS.jpg","contentUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/COLLAGE-DELISSIMOS.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/borges.es\/ca\/blog\/quatre-vinagretes-imprescindibles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/borges.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Quatre vinagretes imprescindibles a la teva taula"}]},{"@type":"WebSite","@id":"https:\/\/borges.es\/ca\/#website","url":"https:\/\/borges.es\/ca\/","name":"Borges","description":"Aqu\u00ed disfrutamos de la cocina saludable y sabrosa. \u00bfTe apuntas?","inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/borges.es\/ca\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60","name":"mortensen","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","caption":"mortensen"},"url":"https:\/\/borges.es\/ca\/blog\/author\/mortensen\/"}]}},"_links":{"self":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts\/2879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/comments?post=2879"}],"version-history":[{"count":1,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts\/2879\/revisions"}],"predecessor-version":[{"id":3312,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts\/2879\/revisions\/3312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/media\/1892"}],"wp:attachment":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/media?parent=2879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/categories?post=2879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/tags?post=2879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}