{"id":2921,"date":"2016-11-14T00:00:00","date_gmt":"2016-11-14T00:00:00","guid":{"rendered":"https:\/\/borges.es\/blog\/oli-oliva-contra-la-diabetis\/"},"modified":"2018-06-05T14:15:43","modified_gmt":"2018-06-05T14:15:43","slug":"oli-oliva-contra-la-diabetis","status":"publish","type":"post","link":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/","title":{"rendered":"L\u2019oli d\u2019oliva verge extra \u00e9s una gran aliat contra la diabetis, que ho sabies?"},"content":{"rendered":"<p>\u00c9s ben sabut que ens encanta l\u2019oli d\u2019oliva verge extra. N\u2019hem parlat en moltes ocasions, n\u2019hem repassat els <a href=\"https:\/\/borges.es\/ca\/oli-oliva-verge-extra-a-la-cuina\/\" target=\"_blank\"><u>usos culinaris<\/u><\/a> i <a href=\"https:\/\/borges.es\/ca\/usos-loli-doliva-mes-enlla-la-cuina\/\" target=\"_blank\"><u>els que no tenen res a veure amb la cuina<\/u><\/a>, tamb\u00e9 els seus maridatges m\u00e9s inesperats, com aquest amb <a href=\"https:\/\/borges.es\/ca\/xocolata-i-oli-doliva\/\" target=\"_blank\"><u>xocolata<\/u><\/a>, i tamb\u00e9 els seus <a href=\"https:\/\/borges.es\/ca\/cinc-beneficis-oli-oliva\/\" target=\"_blank\"><u>principals avantatges en mat\u00e8ria de salut<\/u><\/a>.<\/p>\n<p>Sense perdre aix\u00f2 \u00faltim de vista, avui toca aturar-se en un punt: la seva acci\u00f3 en casos de diabetis, una malaltia que afecta m\u00e9s de 420 milions de persones al m\u00f3n (segons les dades del 2014 de l\u2019<em>Informe mundial sobre la diabetis <\/em>de l\u2019Organitzaci\u00f3 Mundial de la Salut, Ginebra, 2016). La diabetis est\u00e0 molt relacionada amb l\u2019obesitat, la hipertensi\u00f3 i el sedentarisme. Sembla que aproximadament el 50% dels afectats no s\u00f3n conscients de la seva malaltia, una xifra que arriba, en alguns pa\u00efsos, al 80%. Poca broma, oi?<\/p>\n<p>Doncs b\u00e9, com que l\u2019alimentaci\u00f3 \u00e9s salut, en aquest cas no se\u2019n podia quedar al marge. Est\u00e0 demostrat que seguir una dieta mediterr\u00e0nia ajuda de manera significativa a reduir el risc de patir diabetis. Aix\u00ed ho expressen les conclusions de l\u2019estudi Predimed (Prevenci\u00f3 amb Dieta Mediterr\u00e0nia), en qu\u00e8 es va treballar amb diab\u00e8tics o persones que presentaven un risc de patir malalties cardiovasculars.<\/p>\n<p>Al cap d\u2019uns anys, les persones estudiades que havien seguit una dieta mediterr\u00e0nia enriquida amb oli d\u2019oliva verge extra havien redu\u00eft el risc de patir diabetis entre un 40 i un 18% en comparaci\u00f3 amb els que havien seguit una dieta baixa en greixos. A m\u00e9s, havien alentit la progressi\u00f3 de la malaltia un cop diagnosticada i havien retardat el tractament amb medicaments.<\/p>\n<p>I aix\u00ed doncs? El motiu \u00e9s f\u00e0cil d\u2019entendre si sabem distingir entre greixos saludables (insaturats) i no-saludables (saturats i trans). Els primers, presents en l\u2019oli d\u2019oliva verge extra \u2015i en el peix blau i la fruita seca, per exemple\u2015, ajuden a baixar de pes i a prevenir malalties cardiovasculars. Ni tots els greixos s\u00f3n dolents ni \u00e9s aconsellable desterrar-los de la nostra cuina. M\u00e9s clar, l\u2019aigua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9s ben sabut que ens encanta l\u2019oli d\u2019oliva verge extra. N\u2019hem parlat en moltes ocasions, n\u2019hem repassat els usos culinaris&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[88,2044,2043,2023,2010,1954,1892,1816,1792,1791,1784,1777,1773,1771,1761,982],"class_list":["post-2921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-ca","tag-oli-doliva","tag-malaltia","tag-diabetis","tag-oli-doliva-verge-extra","tag-dieta-mediterrania","tag-mediterrania","tag-borges","tag-consells","tag-salut","tag-nutricio","tag-oli","tag-consell","tag-mediterrani","tag-sa","tag-dieta","tag-aceite-de-oliva-virgen-extra-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019oli d\u2019oliva verge extra \u00e9s una gran aliat contra la diabetis, que ho sabies? - Borges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019oli d\u2019oliva verge extra \u00e9s una gran aliat contra la diabetis, que ho sabies? - Borges\" \/>\n<meta property=\"og:description\" content=\"\u00c9s ben sabut que ens encanta l\u2019oli d\u2019oliva verge extra. N\u2019hem parlat en moltes ocasions, n\u2019hem repassat els usos culinaris...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/\" \/>\n<meta property=\"og:site_name\" content=\"Borges\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-14T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-05T14:15:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/POST-20161114.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mortensen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"mortensen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/\"},\"author\":{\"name\":\"mortensen\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\"},\"headline\":\"L\u2019oli d\u2019oliva verge extra \u00e9s una gran aliat contra la diabetis, que ho sabies?\",\"datePublished\":\"2016-11-14T00:00:00+00:00\",\"dateModified\":\"2018-06-05T14:15:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/\"},\"wordCount\":371,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/06\\\/POST-20161114.jpg\",\"keywords\":[\"Oli d'oliva\",\"malaltia\",\"diabetis\",\"oli d'oliva verge extra\",\"dieta mediterr\u00e0nia\",\"mediterr\u00e0nia\",\"borges\",\"consells\",\"salut\",\"nutrici\u00f3\",\"oli\",\"consell\",\"mediterrani\",\"sa\",\"dieta\",\"aceite de oliva virgen extra\"],\"articleSection\":[\"Uncategorized @ca\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/\",\"url\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/\",\"name\":\"L\u2019oli d\u2019oliva verge extra \u00e9s una gran aliat contra la diabetis, que ho sabies? - Borges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/06\\\/POST-20161114.jpg\",\"datePublished\":\"2016-11-14T00:00:00+00:00\",\"dateModified\":\"2018-06-05T14:15:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/06\\\/POST-20161114.jpg\",\"contentUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/06\\\/POST-20161114.jpg\",\"width\":828,\"height\":580},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/oli-oliva-contra-la-diabetis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/borges.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019oli d\u2019oliva verge extra \u00e9s una gran aliat contra la diabetis, que ho sabies?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/borges.es\\\/ca\\\/\",\"name\":\"Borges\",\"description\":\"Aqu\u00ed disfrutamos de la cocina saludable y sabrosa. \u00bfTe apuntas?\",\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#\\\/schema\\\/person\\\/f9ce1a648d852dd65f2508352b7f9a60\",\"name\":\"mortensen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g\",\"caption\":\"mortensen\"},\"url\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/author\\\/mortensen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019oli d\u2019oliva verge extra \u00e9s una gran aliat contra la diabetis, que ho sabies? - Borges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/","og_locale":"ca_ES","og_type":"article","og_title":"L\u2019oli d\u2019oliva verge extra \u00e9s una gran aliat contra la diabetis, que ho sabies? - Borges","og_description":"\u00c9s ben sabut que ens encanta l\u2019oli d\u2019oliva verge extra. N\u2019hem parlat en moltes ocasions, n\u2019hem repassat els usos culinaris...","og_url":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/","og_site_name":"Borges","article_published_time":"2016-11-14T00:00:00+00:00","article_modified_time":"2018-06-05T14:15:43+00:00","og_image":[{"width":828,"height":580,"url":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/POST-20161114.jpg","type":"image\/jpeg"}],"author":"mortensen","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"mortensen","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/#article","isPartOf":{"@id":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/"},"author":{"name":"mortensen","@id":"https:\/\/borges.es\/ca\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60"},"headline":"L\u2019oli d\u2019oliva verge extra \u00e9s una gran aliat contra la diabetis, que ho sabies?","datePublished":"2016-11-14T00:00:00+00:00","dateModified":"2018-06-05T14:15:43+00:00","mainEntityOfPage":{"@id":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/"},"wordCount":371,"commentCount":0,"image":{"@id":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/#primaryimage"},"thumbnailUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/POST-20161114.jpg","keywords":["Oli d'oliva","malaltia","diabetis","oli d'oliva verge extra","dieta mediterr\u00e0nia","mediterr\u00e0nia","borges","consells","salut","nutrici\u00f3","oli","consell","mediterrani","sa","dieta","aceite de oliva virgen extra"],"articleSection":["Uncategorized @ca"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/","url":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/","name":"L\u2019oli d\u2019oliva verge extra \u00e9s una gran aliat contra la diabetis, que ho sabies? - Borges","isPartOf":{"@id":"https:\/\/borges.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/#primaryimage"},"image":{"@id":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/#primaryimage"},"thumbnailUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/POST-20161114.jpg","datePublished":"2016-11-14T00:00:00+00:00","dateModified":"2018-06-05T14:15:43+00:00","author":{"@id":"https:\/\/borges.es\/ca\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60"},"breadcrumb":{"@id":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/#primaryimage","url":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/POST-20161114.jpg","contentUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/06\/POST-20161114.jpg","width":828,"height":580},{"@type":"BreadcrumbList","@id":"https:\/\/borges.es\/ca\/blog\/oli-oliva-contra-la-diabetis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/borges.es\/ca\/"},{"@type":"ListItem","position":2,"name":"L\u2019oli d\u2019oliva verge extra \u00e9s una gran aliat contra la diabetis, que ho sabies?"}]},{"@type":"WebSite","@id":"https:\/\/borges.es\/ca\/#website","url":"https:\/\/borges.es\/ca\/","name":"Borges","description":"Aqu\u00ed disfrutamos de la cocina saludable y sabrosa. \u00bfTe apuntas?","inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/borges.es\/ca\/#\/schema\/person\/f9ce1a648d852dd65f2508352b7f9a60","name":"mortensen","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd2bd5aa753e679cd6f252540910ce11cd98c07228cac0664dcedefa61649290?s=96&d=mm&r=g","caption":"mortensen"},"url":"https:\/\/borges.es\/ca\/blog\/author\/mortensen\/"}]}},"_links":{"self":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts\/2921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/comments?post=2921"}],"version-history":[{"count":1,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts\/2921\/revisions"}],"predecessor-version":[{"id":3275,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts\/2921\/revisions\/3275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/media\/1956"}],"wp:attachment":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/media?parent=2921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/categories?post=2921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/tags?post=2921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}