{"id":4955,"date":"2018-10-02T14:17:59","date_gmt":"2018-10-02T14:17:59","guid":{"rendered":"https:\/\/borges.es\/?p=4955"},"modified":"2018-10-04T10:25:22","modified_gmt":"2018-10-04T10:25:22","slug":"origen-dels-canelons","status":"publish","type":"post","link":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/","title":{"rendered":"D\u2019on venen els canelons?"},"content":{"rendered":"<p>Sabies que la ciutat del m\u00f3n on hi ha m\u00e9s <em>pizzeries\u00a0<\/em>\u00e9s Marsella?Aquesta dada sorprenent \u00e9s un bon exemple de la internacionalitzaci\u00f3 de la cuina italiana, que t\u00e9 seguidors arreu del m\u00f3n gr\u00e0cies a les seves delicioses pastes, els vins de somni i els productes multicolors de l\u2019hort mediterrani.<\/p>\n<p>Un altre exemple de recepta italiana que es consumeix m\u00e9s en altres llocs que a It\u00e0lia s\u00f3n els canelons, que a Barcelona van introduir, al segle XIX, diversos cuiners italians que treballaven en algunes llars de la burgesia local. El desenlla\u00e7 de la hist\u00f2ria \u00e9s conegut de sobres: la seva fama es va estendre r\u00e0pidament per totes les classes socials i comen\u00e7ament del segle XX ja els trobem en alguns receptaris catalans.<\/p>\n<p>Avui, els canelons no nom\u00e9s s\u00f3n un plat t\u00edpic de Catalunya \u2014molt com\u00fa el 26 de desembre, Sant Esteve, el qu\u00e8 les fam\u00edlies menjaven canelons per aprofitar les restes del tiberi del dia de Nadal\u2014, sin\u00f3 de tot Espanya i diversos pa\u00efsos de l\u2019Am\u00e8rica Llatina.<\/p>\n<p>Com sol passar amb totes les receptes fascinants, dels cl\u00e0ssics canelons amb beixamel, carn variada i una mica de pat\u00e9 per donar-los consist\u00e8ncia se n\u2019han fet un munt de versions en nombrosos gastrobars moderns. Beixamels personalitzades, farcits d\u2019ultramar i fins i tot rotlles de pasta elaborats amb carbass\u00f3\u2026 Ja tenim aqu\u00ed el canel\u00f3 del segle XXI! I \u00e9s bon\u00edssim!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabies que la ciutat del m\u00f3n on hi ha m\u00e9s pizzeries\u00a0\u00e9s Marsella?Aquesta dada sorprenent \u00e9s un bon exemple de la&#8230;<\/p>\n","protected":false},"author":63,"featured_media":4953,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[2526],"class_list":["post-4955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-ca","tag-canalons"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u2019on venen els canelons? - Borges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u2019on venen els canelons? - Borges\" \/>\n<meta property=\"og:description\" content=\"Sabies que la ciutat del m\u00f3n on hi ha m\u00e9s pizzeries\u00a0\u00e9s Marsella?Aquesta dada sorprenent \u00e9s un bon exemple de la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/\" \/>\n<meta property=\"og:site_name\" content=\"Borges\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-02T14:17:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-04T10:25:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borges1896.com\/app\/uploads\/\/2018\/10\/MI-WW-20181004.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1687\" \/>\n\t<meta property=\"og:image:height\" content=\"1126\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"S\u00edlvia Serra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mortensen\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00edlvia Serra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/\"},\"author\":{\"name\":\"S\u00edlvia Serra\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#\\\/schema\\\/person\\\/4d4336303ff947bb61578b6173db1cb3\"},\"headline\":\"D\u2019on venen els canelons?\",\"datePublished\":\"2018-10-02T14:17:59+00:00\",\"dateModified\":\"2018-10-04T10:25:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/\"},\"wordCount\":253,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/10\\\/MI-WW-20181004.jpg\",\"keywords\":[\"canalons\"],\"articleSection\":[\"Uncategorized @ca\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/\",\"url\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/\",\"name\":\"D\u2019on venen els canelons? - Borges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/10\\\/MI-WW-20181004.jpg\",\"datePublished\":\"2018-10-02T14:17:59+00:00\",\"dateModified\":\"2018-10-04T10:25:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#\\\/schema\\\/person\\\/4d4336303ff947bb61578b6173db1cb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/#primaryimage\",\"url\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/10\\\/MI-WW-20181004.jpg\",\"contentUrl\":\"https:\\\/\\\/borges1896.com\\\/app\\\/uploads\\\/\\\/2018\\\/10\\\/MI-WW-20181004.jpg\",\"width\":1687,\"height\":1126,\"caption\":\"Borges - Canelons\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/origen-dels-canelons\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/borges.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u2019on venen els canelons?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/borges.es\\\/ca\\\/\",\"name\":\"Borges\",\"description\":\"Aqu\u00ed disfrutamos de la cocina saludable y sabrosa. \u00bfTe apuntas?\",\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/borges.es\\\/ca\\\/#\\\/schema\\\/person\\\/4d4336303ff947bb61578b6173db1cb3\",\"name\":\"S\u00edlvia Serra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34074626096365f59765ad518fb0221300ade7a2b5a585b878a1aec5d37810e3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34074626096365f59765ad518fb0221300ade7a2b5a585b878a1aec5d37810e3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34074626096365f59765ad518fb0221300ade7a2b5a585b878a1aec5d37810e3?s=96&d=mm&r=g\",\"caption\":\"S\u00edlvia Serra\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/mortensen\"],\"url\":\"https:\\\/\\\/borges.es\\\/ca\\\/blog\\\/author\\\/silvia-serra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u2019on venen els canelons? - Borges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/","og_locale":"ca_ES","og_type":"article","og_title":"D\u2019on venen els canelons? - Borges","og_description":"Sabies que la ciutat del m\u00f3n on hi ha m\u00e9s pizzeries\u00a0\u00e9s Marsella?Aquesta dada sorprenent \u00e9s un bon exemple de la...","og_url":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/","og_site_name":"Borges","article_published_time":"2018-10-02T14:17:59+00:00","article_modified_time":"2018-10-04T10:25:22+00:00","og_image":[{"width":1687,"height":1126,"url":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/10\/MI-WW-20181004.jpg","type":"image\/jpeg"}],"author":"S\u00edlvia Serra","twitter_card":"summary_large_image","twitter_creator":"@mortensen","twitter_misc":{"Escrit per":"S\u00edlvia Serra","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/#article","isPartOf":{"@id":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/"},"author":{"name":"S\u00edlvia Serra","@id":"https:\/\/borges.es\/ca\/#\/schema\/person\/4d4336303ff947bb61578b6173db1cb3"},"headline":"D\u2019on venen els canelons?","datePublished":"2018-10-02T14:17:59+00:00","dateModified":"2018-10-04T10:25:22+00:00","mainEntityOfPage":{"@id":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/"},"wordCount":253,"commentCount":0,"image":{"@id":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/#primaryimage"},"thumbnailUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/10\/MI-WW-20181004.jpg","keywords":["canalons"],"articleSection":["Uncategorized @ca"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/","url":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/","name":"D\u2019on venen els canelons? - Borges","isPartOf":{"@id":"https:\/\/borges.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/#primaryimage"},"image":{"@id":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/#primaryimage"},"thumbnailUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/10\/MI-WW-20181004.jpg","datePublished":"2018-10-02T14:17:59+00:00","dateModified":"2018-10-04T10:25:22+00:00","author":{"@id":"https:\/\/borges.es\/ca\/#\/schema\/person\/4d4336303ff947bb61578b6173db1cb3"},"breadcrumb":{"@id":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/#primaryimage","url":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/10\/MI-WW-20181004.jpg","contentUrl":"https:\/\/borges1896.com\/app\/uploads\/\/2018\/10\/MI-WW-20181004.jpg","width":1687,"height":1126,"caption":"Borges - Canelons"},{"@type":"BreadcrumbList","@id":"https:\/\/borges.es\/ca\/blog\/origen-dels-canelons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/borges.es\/ca\/"},{"@type":"ListItem","position":2,"name":"D\u2019on venen els canelons?"}]},{"@type":"WebSite","@id":"https:\/\/borges.es\/ca\/#website","url":"https:\/\/borges.es\/ca\/","name":"Borges","description":"Aqu\u00ed disfrutamos de la cocina saludable y sabrosa. \u00bfTe apuntas?","inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/borges.es\/ca\/#\/schema\/person\/4d4336303ff947bb61578b6173db1cb3","name":"S\u00edlvia Serra","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/34074626096365f59765ad518fb0221300ade7a2b5a585b878a1aec5d37810e3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34074626096365f59765ad518fb0221300ade7a2b5a585b878a1aec5d37810e3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34074626096365f59765ad518fb0221300ade7a2b5a585b878a1aec5d37810e3?s=96&d=mm&r=g","caption":"S\u00edlvia Serra"},"sameAs":["https:\/\/x.com\/mortensen"],"url":"https:\/\/borges.es\/ca\/blog\/author\/silvia-serra\/"}]}},"_links":{"self":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts\/4955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/comments?post=4955"}],"version-history":[{"count":2,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts\/4955\/revisions"}],"predecessor-version":[{"id":4963,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/posts\/4955\/revisions\/4963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/media\/4953"}],"wp:attachment":[{"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/media?parent=4955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/categories?post=4955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borges.es\/ca\/wp-json\/wp\/v2\/tags?post=4955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}